{"id":2121,"date":"2021-10-29T14:46:19","date_gmt":"2021-10-29T12:46:19","guid":{"rendered":"https:\/\/bestxxxvr.com\/vr-videos\/?p=2121"},"modified":"2022-12-02T19:09:04","modified_gmt":"2022-12-02T18:09:04","slug":"mighty-wizard","status":"publish","type":"post","link":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/","title":{"rendered":"Mighty Wizard"},"content":{"rendered":"<p><strong>Mighty Wizard<\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mighty Wizard <\/p>\n","protected":false},"author":1,"featured_media":2122,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[137],"tags":[12,5,23,24,13,74,83,7,30,10,11,15,20,16,84,17,71,199,22,51,41,36],"actors":[89],"class_list":["post-2121","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-vrconk","tag-12","tag-3d","tag-4k","tag-5k","tag-60-fps","tag-6k","tag-asian","tag-blow-job","tag-close-ups","tag-cowgirl","tag-cumshots","tag-doggy-style","tag-english-speech","tag-hardcore","tag-interracial","tag-missionary","tag-pigtail-ponytail","tag-porn-parody","tag-pov","tag-reverse-cowgirl","tag-shaved-pussy","tag-stockings","post_format-post-format-video","actors-alexia-anders"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mighty Wizard<\/title>\n<meta name=\"description\" content=\"Mighty Wizard\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mighty Wizard\" \/>\n<meta property=\"og:description\" content=\"Mighty Wizard\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/\" \/>\n<meta property=\"og:site_name\" content=\"Best XXX VR\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T12:46:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-02T18:09:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bestxxxvr.com\/vr-videos\/wp-content\/uploads\/2022\/12\/Mighty-Wizard.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"830\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Best XXX VR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Best XXX VR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/\"},\"author\":{\"name\":\"Best XXX VR\",\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/#\\\/schema\\\/person\\\/3d7e9ba41ecfa06023111fdea2249aeb\"},\"headline\":\"Mighty Wizard\",\"datePublished\":\"2021-10-29T12:46:19+00:00\",\"dateModified\":\"2022-12-02T18:09:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/#\\\/schema\\\/person\\\/3d7e9ba41ecfa06023111fdea2249aeb\"},\"image\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mighty-Wizard.jpg\",\"keywords\":[\"180\u00b0\",\"3D\",\"4K\",\"5K\",\"60 FPS\",\"6K\",\"asian\",\"blow job\",\"close ups\",\"cowgirl\",\"cumshots\",\"doggy style\",\"english speech\",\"hardcore\",\"interracial\",\"missionary\",\"pigtail \\\/ ponytail\",\"porn parody\",\"POV\",\"reverse cowgirl\",\"shaved pussy\",\"stockings\"],\"articleSection\":[\"VRConk\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/\",\"url\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/\",\"name\":\"Mighty Wizard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mighty-Wizard.jpg\",\"datePublished\":\"2021-10-29T12:46:19+00:00\",\"dateModified\":\"2022-12-02T18:09:04+00:00\",\"description\":\"Mighty Wizard\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mighty-Wizard.jpg\",\"contentUrl\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mighty-Wizard.jpg\",\"width\":786,\"height\":830,\"caption\":\"Mighty Wizard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/vrconk\\\/mighty-wizard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mighty Wizard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/#website\",\"url\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/\",\"name\":\"Best XXX VR\",\"description\":\"The Best XXX VR Porn On The Web!\",\"publisher\":{\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/#\\\/schema\\\/person\\\/3d7e9ba41ecfa06023111fdea2249aeb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/#\\\/schema\\\/person\\\/3d7e9ba41ecfa06023111fdea2249aeb\",\"name\":\"Best XXX VR\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g\",\"caption\":\"Best XXX VR\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\"],\"url\":\"https:\\\/\\\/bestxxxvr.com\\\/vr-videos\\\/author\\\/best-xxx-vr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mighty Wizard","description":"Mighty Wizard","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/","og_locale":"en_US","og_type":"article","og_title":"Mighty Wizard","og_description":"Mighty Wizard","og_url":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/","og_site_name":"Best XXX VR","article_published_time":"2021-10-29T12:46:19+00:00","article_modified_time":"2022-12-02T18:09:04+00:00","og_image":[{"width":786,"height":830,"url":"https:\/\/bestxxxvr.com\/vr-videos\/wp-content\/uploads\/2022\/12\/Mighty-Wizard.jpg","type":"image\/jpeg"}],"author":"Best XXX VR","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Best XXX VR"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#article","isPartOf":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/"},"author":{"name":"Best XXX VR","@id":"https:\/\/bestxxxvr.com\/vr-videos\/#\/schema\/person\/3d7e9ba41ecfa06023111fdea2249aeb"},"headline":"Mighty Wizard","datePublished":"2021-10-29T12:46:19+00:00","dateModified":"2022-12-02T18:09:04+00:00","mainEntityOfPage":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/"},"wordCount":4,"publisher":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/#\/schema\/person\/3d7e9ba41ecfa06023111fdea2249aeb"},"image":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#primaryimage"},"thumbnailUrl":"https:\/\/bestxxxvr.com\/vr-videos\/wp-content\/uploads\/2022\/12\/Mighty-Wizard.jpg","keywords":["180\u00b0","3D","4K","5K","60 FPS","6K","asian","blow job","close ups","cowgirl","cumshots","doggy style","english speech","hardcore","interracial","missionary","pigtail \/ ponytail","porn parody","POV","reverse cowgirl","shaved pussy","stockings"],"articleSection":["VRConk"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/","url":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/","name":"Mighty Wizard","isPartOf":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#primaryimage"},"image":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#primaryimage"},"thumbnailUrl":"https:\/\/bestxxxvr.com\/vr-videos\/wp-content\/uploads\/2022\/12\/Mighty-Wizard.jpg","datePublished":"2021-10-29T12:46:19+00:00","dateModified":"2022-12-02T18:09:04+00:00","description":"Mighty Wizard","breadcrumb":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#primaryimage","url":"https:\/\/bestxxxvr.com\/vr-videos\/wp-content\/uploads\/2022\/12\/Mighty-Wizard.jpg","contentUrl":"https:\/\/bestxxxvr.com\/vr-videos\/wp-content\/uploads\/2022\/12\/Mighty-Wizard.jpg","width":786,"height":830,"caption":"Mighty Wizard"},{"@type":"BreadcrumbList","@id":"https:\/\/bestxxxvr.com\/vr-videos\/vrconk\/mighty-wizard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bestxxxvr.com\/vr-videos\/"},{"@type":"ListItem","position":2,"name":"Mighty Wizard"}]},{"@type":"WebSite","@id":"https:\/\/bestxxxvr.com\/vr-videos\/#website","url":"https:\/\/bestxxxvr.com\/vr-videos\/","name":"Best XXX VR","description":"The Best XXX VR Porn On The Web!","publisher":{"@id":"https:\/\/bestxxxvr.com\/vr-videos\/#\/schema\/person\/3d7e9ba41ecfa06023111fdea2249aeb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bestxxxvr.com\/vr-videos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/bestxxxvr.com\/vr-videos\/#\/schema\/person\/3d7e9ba41ecfa06023111fdea2249aeb","name":"Best XXX VR","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g","caption":"Best XXX VR"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/02b5694040976ce09fd2653103ec9d59f581518fa17a6cd796039f0f306cf7f4?s=96&d=mm&r=g"},"sameAs":["https:\/\/bestxxxvr.com\/vr-videos"],"url":"https:\/\/bestxxxvr.com\/vr-videos\/author\/best-xxx-vr\/"}]}},"_links":{"self":[{"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/posts\/2121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/comments?post=2121"}],"version-history":[{"count":0,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/posts\/2121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/media\/2122"}],"wp:attachment":[{"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/media?parent=2121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/categories?post=2121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/tags?post=2121"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/bestxxxvr.com\/vr-videos\/wp-json\/wp\/v2\/actors?post=2121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}